{"id":52432,"date":"2026-03-27T00:00:00","date_gmt":"2026-03-27T00:00:00","guid":{"rendered":"https:\/\/www.callandplay.com\/yamaha-ybb-641e-tuba-sib\/"},"modified":"2026-09-01T14:38:04","modified_gmt":"2026-09-01T14:38:04","slug":"yamaha-ybb-641e-tuba-sib","status":"publish","type":"product","link":"https:\/\/www.callandplay.com\/ca\/yamaha-ybb-641e-tuba-sib\/","title":{"rendered":"YAMAHA YBB 641E TUBA Sib"},"content":{"rendered":"<p>La tuba en si doble bemol profesional 641 incorpora una configuraci\u00f3n de cilindros para producir un sonido tradicional teut\u00f3nico, con una entonaci\u00f3n precisa y una facilidad de interpretaci\u00f3n \u00fanicamente posibles gracias a la ingenier\u00eda moderna. Se caracteriza por un sonido c\u00e1lido y oscuro con abundantes colores tonales. Serie Professional: clave: si doble bemol; material: metal amarillo; v\u00e1lvulas de acci\u00f3n frontal: 4 cilindros; campana: 419 mm (16-1\/2 pulgadas); taladro: 20,6 mm (0,811 pulgadas); acabado: laca transparente.<\/p>","protected":false},"excerpt":{"rendered":"<p>La tuba en si doble bemol profesional 641 incorpora una configuraci\u00f3n de cilindros para producir un sonido tradicional teut\u00f3nico, con una entonaci\u00f3n precisa y una facilidad de interpretaci\u00f3n \u00fanicamente posibles gracias a la ingenier\u00eda moderna. Se caracteriza por un sonido c\u00e1lido y oscuro con abundantes colores tonales. Serie Professional: clave: si doble bemol; material: metal amarillo; v\u00e1lvulas de acci\u00f3n frontal: 4 cilindros; campana: 419 mm (16-1\/2 pulgadas); taladro: 20,6 mm (0,811 pulgadas); acabado: laca transparente.<\/p>","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[1768],"product_tag":[],"class_list":["post-52432","product","type-product","status-publish","product_cat-otros-instrumentos-de-viento-otros-instrumentos-de-viento","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>YAMAHA YBB 641E TUBA Sib - Call&amp;Play<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.callandplay.com\/ca\/yamaha-ybb-641e-tuba-sib\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"YAMAHA YBB 641E TUBA Sib - Call&amp;Play\" \/>\n<meta property=\"og:description\" content=\"La tuba en si doble bemol profesional 641 incorpora una configuraci\u00f3n de cilindros para producir un sonido tradicional teut\u00f3nico, con una entonaci\u00f3n precisa y una facilidad de interpretaci\u00f3n \u00fanicamente posibles gracias a la ingenier\u00eda moderna. Se caracteriza por un sonido c\u00e1lido y oscuro con abundantes colores tonales. Serie Professional: clave: si doble bemol; material: metal amarillo; v\u00e1lvulas de acci\u00f3n frontal: 4 cilindros; campana: 419 mm (16-1\/2 pulgadas); taladro: 20,6 mm (0,811 pulgadas); acabado: laca transparente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.callandplay.com\/ca\/yamaha-ybb-641e-tuba-sib\/\" \/>\n<meta property=\"og:site_name\" content=\"Call&amp;Play\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/callandplay\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:38:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/yamaha-ybb-641e-tuba-sib\\\/\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/yamaha-ybb-641e-tuba-sib\\\/\",\"name\":\"YAMAHA YBB 641E TUBA Sib - Call&amp;Play\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#website\"},\"datePublished\":\"2026-03-27T00:00:00+00:00\",\"dateModified\":\"2026-09-01T14:38:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/yamaha-ybb-641e-tuba-sib\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.callandplay.com\\\/yamaha-ybb-641e-tuba-sib\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/yamaha-ybb-641e-tuba-sib\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.callandplay.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/www.callandplay.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"YAMAHA YBB 641E TUBA Sib\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#website\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/\",\"name\":\"Call&Play\",\"description\":\"Alquiler de backline e instrumentos musicales\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.callandplay.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#organization\",\"name\":\"Call&Play\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-cropped-logo-black_con_sombra.png\",\"contentUrl\":\"https:\\\/\\\/www.callandplay.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-cropped-logo-black_con_sombra.png\",\"width\":512,\"height\":512,\"caption\":\"Call&Play\"},\"image\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/callandplay\",\"https:\\\/\\\/www.instagram.com\\\/call_and_play\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"YAMAHA YBB 641E TUBA Sib - Call&amp;Play","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.callandplay.com\/ca\/yamaha-ybb-641e-tuba-sib\/","og_locale":"ca_ES","og_type":"article","og_title":"YAMAHA YBB 641E TUBA Sib - Call&amp;Play","og_description":"La tuba en si doble bemol profesional 641 incorpora una configuraci\u00f3n de cilindros para producir un sonido tradicional teut\u00f3nico, con una entonaci\u00f3n precisa y una facilidad de interpretaci\u00f3n \u00fanicamente posibles gracias a la ingenier\u00eda moderna. Se caracteriza por un sonido c\u00e1lido y oscuro con abundantes colores tonales. Serie Professional: clave: si doble bemol; material: metal amarillo; v\u00e1lvulas de acci\u00f3n frontal: 4 cilindros; campana: 419 mm (16-1\/2 pulgadas); taladro: 20,6 mm (0,811 pulgadas); acabado: laca transparente.","og_url":"https:\/\/www.callandplay.com\/ca\/yamaha-ybb-641e-tuba-sib\/","og_site_name":"Call&amp;Play","article_publisher":"https:\/\/www.facebook.com\/callandplay","article_modified_time":"2026-09-01T14:38:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.callandplay.com\/yamaha-ybb-641e-tuba-sib\/","url":"https:\/\/www.callandplay.com\/yamaha-ybb-641e-tuba-sib\/","name":"YAMAHA YBB 641E TUBA Sib - Call&amp;Play","isPartOf":{"@id":"https:\/\/www.callandplay.com\/#website"},"datePublished":"2026-03-27T00:00:00+00:00","dateModified":"2026-09-01T14:38:04+00:00","breadcrumb":{"@id":"https:\/\/www.callandplay.com\/yamaha-ybb-641e-tuba-sib\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.callandplay.com\/yamaha-ybb-641e-tuba-sib\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.callandplay.com\/yamaha-ybb-641e-tuba-sib\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.callandplay.com\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.callandplay.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"YAMAHA YBB 641E TUBA Sib"}]},{"@type":"WebSite","@id":"https:\/\/www.callandplay.com\/#website","url":"https:\/\/www.callandplay.com\/","name":"Call&Play","description":"Alquiler de backline e instrumentos musicales","publisher":{"@id":"https:\/\/www.callandplay.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.callandplay.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.callandplay.com\/#organization","name":"Call&Play","url":"https:\/\/www.callandplay.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.callandplay.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.callandplay.com\/wp-content\/uploads\/2021\/06\/cropped-cropped-logo-black_con_sombra.png","contentUrl":"https:\/\/www.callandplay.com\/wp-content\/uploads\/2021\/06\/cropped-cropped-logo-black_con_sombra.png","width":512,"height":512,"caption":"Call&Play"},"image":{"@id":"https:\/\/www.callandplay.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/callandplay","https:\/\/www.instagram.com\/call_and_play\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/product\/52432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/comments?post=52432"}],"version-history":[{"count":1,"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/product\/52432\/revisions"}],"predecessor-version":[{"id":55242,"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/product\/52432\/revisions\/55242"}],"wp:attachment":[{"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/media?parent=52432"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/product_brand?post=52432"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/product_cat?post=52432"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.callandplay.com\/ca\/wp-json\/wp\/v2\/product_tag?post=52432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}