{"id":50773,"date":"2025-03-22T11:10:36","date_gmt":"2025-03-22T11:10:36","guid":{"rendered":"https:\/\/www.callandplay.com\/?post_type=eventos&#038;p=50773"},"modified":"2026-02-02T11:28:10","modified_gmt":"2026-02-02T11:28:10","slug":"concierto-para-dos-pianos-en-la-universidad-de-navarra","status":"publish","type":"eventos","link":"https:\/\/www.callandplay.com\/en\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/","title":{"rendered":"Concierto para dos pianos en la Universidad de Navarra"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Cyprien Katsaris y Pablo Galdo ofrecieron un concierto para dos pianos en el Museo de la Universidad de Navarra el 21 de marzo. Presentaron un recorrido por la mejor m\u00fasica rom\u00e1ntica, inspirada en melod\u00edas populares h\u00fangaras, brasileras o espa\u00f1olas, con el piano como instrumento solista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los pianos fueron dos Steinway D-274. El programa del concierto incluy\u00f3 las bellas piezas de Franz Liszt inspiradas en la m\u00fasica h\u00fangara, la <em>Fantas\u00eda para \u00f3rgano mec\u00e1nico<\/em>&nbsp;de Mozart, arreglada para dos pianos y las populares obras de&nbsp;<em>Carmen<\/em>&nbsp;de Bizet y el&nbsp;<em>Bolero<\/em>&nbsp;de Ravel y que incluye<em>&nbsp;Scaramouche<\/em>&nbsp;de Milhaud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"featured_media":50774,"template":"","categorias-de-eventos":[23],"class_list":["post-50773","eventos","type-eventos","status-publish","has-post-thumbnail","hentry","categorias-de-eventos-pianos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concierto para dos pianos en la Universidad de Navarra - Call&amp;Play<\/title>\n<meta name=\"description\" content=\"Concierto para dos pianos Steinway en la Universidad de Navarra. Concierto de obras de Franz Liszt, Bizet y Ravel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.callandplay.com\/en\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concierto para dos pianos en la Universidad de Navarra - Call&amp;Play\" \/>\n<meta property=\"og:description\" content=\"Concierto para dos pianos Steinway en la Universidad de Navarra. Concierto de obras de Franz Liszt, Bizet y Ravel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.callandplay.com\/en\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/\" \/>\n<meta property=\"og:site_name\" content=\"Call&amp;Play\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/callandplay\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T11:28:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.callandplay.com\/wp-content\/uploads\/2026\/02\/Dos-Steinway-en-Univ-Navarra-03-2025-ok-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1597\" \/>\n\t<meta property=\"og:image:height\" content=\"1065\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/eventos\\\/concierto-para-dos-pianos-en-la-universidad-de-navarra\\\/\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/eventos\\\/concierto-para-dos-pianos-en-la-universidad-de-navarra\\\/\",\"name\":\"Concierto para dos pianos en la Universidad de Navarra - Call&amp;Play\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/eventos\\\/concierto-para-dos-pianos-en-la-universidad-de-navarra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/eventos\\\/concierto-para-dos-pianos-en-la-universidad-de-navarra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.callandplay.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Dos-Steinway-en-Univ-Navarra-03-2025-ok-web.jpg\",\"datePublished\":\"2025-03-22T11:10:36+00:00\",\"dateModified\":\"2026-02-02T11:28:10+00:00\",\"description\":\"Concierto para dos pianos Steinway en la Universidad de Navarra. Concierto de obras de Franz Liszt, Bizet y Ravel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/eventos\\\/concierto-para-dos-pianos-en-la-universidad-de-navarra\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.callandplay.com\\\/eventos\\\/concierto-para-dos-pianos-en-la-universidad-de-navarra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/eventos\\\/concierto-para-dos-pianos-en-la-universidad-de-navarra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Dos-Steinway-en-Univ-Navarra-03-2025-ok-web.jpg\",\"contentUrl\":\"https:\\\/\\\/www.callandplay.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Dos-Steinway-en-Univ-Navarra-03-2025-ok-web.jpg\",\"width\":1597,\"height\":1065},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/eventos\\\/concierto-para-dos-pianos-en-la-universidad-de-navarra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.callandplay.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/www.callandplay.com\\\/en\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Concierto para dos pianos en la Universidad de Navarra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#website\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/\",\"name\":\"Call&Play\",\"description\":\"Alquiler de backline e instrumentos musicales\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.callandplay.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#organization\",\"name\":\"Call&Play\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.callandplay.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-cropped-logo-black_con_sombra.png\",\"contentUrl\":\"https:\\\/\\\/www.callandplay.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-cropped-logo-black_con_sombra.png\",\"width\":512,\"height\":512,\"caption\":\"Call&Play\"},\"image\":{\"@id\":\"https:\\\/\\\/www.callandplay.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/callandplay\",\"https:\\\/\\\/www.instagram.com\\\/call_and_play\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concierto para dos pianos en la Universidad de Navarra - Call&amp;Play","description":"Concierto para dos pianos Steinway en la Universidad de Navarra. Concierto de obras de Franz Liszt, Bizet y Ravel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.callandplay.com\/en\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/","og_locale":"en_GB","og_type":"article","og_title":"Concierto para dos pianos en la Universidad de Navarra - Call&amp;Play","og_description":"Concierto para dos pianos Steinway en la Universidad de Navarra. Concierto de obras de Franz Liszt, Bizet y Ravel.","og_url":"https:\/\/www.callandplay.com\/en\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/","og_site_name":"Call&amp;Play","article_publisher":"https:\/\/www.facebook.com\/callandplay","article_modified_time":"2026-02-02T11:28:10+00:00","og_image":[{"width":1597,"height":1065,"url":"https:\/\/www.callandplay.com\/wp-content\/uploads\/2026\/02\/Dos-Steinway-en-Univ-Navarra-03-2025-ok-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.callandplay.com\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/","url":"https:\/\/www.callandplay.com\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/","name":"Concierto para dos pianos en la Universidad de Navarra - Call&amp;Play","isPartOf":{"@id":"https:\/\/www.callandplay.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.callandplay.com\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/#primaryimage"},"image":{"@id":"https:\/\/www.callandplay.com\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.callandplay.com\/wp-content\/uploads\/2026\/02\/Dos-Steinway-en-Univ-Navarra-03-2025-ok-web.jpg","datePublished":"2025-03-22T11:10:36+00:00","dateModified":"2026-02-02T11:28:10+00:00","description":"Concierto para dos pianos Steinway en la Universidad de Navarra. Concierto de obras de Franz Liszt, Bizet y Ravel.","breadcrumb":{"@id":"https:\/\/www.callandplay.com\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.callandplay.com\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.callandplay.com\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/#primaryimage","url":"https:\/\/www.callandplay.com\/wp-content\/uploads\/2026\/02\/Dos-Steinway-en-Univ-Navarra-03-2025-ok-web.jpg","contentUrl":"https:\/\/www.callandplay.com\/wp-content\/uploads\/2026\/02\/Dos-Steinway-en-Univ-Navarra-03-2025-ok-web.jpg","width":1597,"height":1065},{"@type":"BreadcrumbList","@id":"https:\/\/www.callandplay.com\/eventos\/concierto-para-dos-pianos-en-la-universidad-de-navarra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.callandplay.com\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.callandplay.com\/en\/eventos\/"},{"@type":"ListItem","position":3,"name":"Concierto para dos pianos en la Universidad de Navarra"}]},{"@type":"WebSite","@id":"https:\/\/www.callandplay.com\/#website","url":"https:\/\/www.callandplay.com\/","name":"Call&Play","description":"Alquiler de backline e instrumentos musicales","publisher":{"@id":"https:\/\/www.callandplay.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.callandplay.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.callandplay.com\/#organization","name":"Call&Play","url":"https:\/\/www.callandplay.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.callandplay.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.callandplay.com\/wp-content\/uploads\/2021\/06\/cropped-cropped-logo-black_con_sombra.png","contentUrl":"https:\/\/www.callandplay.com\/wp-content\/uploads\/2021\/06\/cropped-cropped-logo-black_con_sombra.png","width":512,"height":512,"caption":"Call&Play"},"image":{"@id":"https:\/\/www.callandplay.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/callandplay","https:\/\/www.instagram.com\/call_and_play\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.callandplay.com\/en\/wp-json\/wp\/v2\/eventos\/50773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.callandplay.com\/en\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.callandplay.com\/en\/wp-json\/wp\/v2\/types\/eventos"}],"version-history":[{"count":2,"href":"https:\/\/www.callandplay.com\/en\/wp-json\/wp\/v2\/eventos\/50773\/revisions"}],"predecessor-version":[{"id":50777,"href":"https:\/\/www.callandplay.com\/en\/wp-json\/wp\/v2\/eventos\/50773\/revisions\/50777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.callandplay.com\/en\/wp-json\/wp\/v2\/media\/50774"}],"wp:attachment":[{"href":"https:\/\/www.callandplay.com\/en\/wp-json\/wp\/v2\/media?parent=50773"}],"wp:term":[{"taxonomy":"categorias-de-eventos","embeddable":true,"href":"https:\/\/www.callandplay.com\/en\/wp-json\/wp\/v2\/categorias-de-eventos?post=50773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}